{"id":12582,"date":"2026-02-08T19:12:46","date_gmt":"2026-02-08T23:12:46","guid":{"rendered":"https:\/\/quizgp.com\/Hoa-Now\/?page_id=12582"},"modified":"2026-02-08T19:12:50","modified_gmt":"2026-02-08T23:12:50","slug":"architectural","status":"publish","type":"page","link":"https:\/\/quizgp.com\/Hoa-Now\/architectural\/","title":{"rendered":"Architectural Services"},"content":{"rendered":"\n<!-- FB Like Button Starbit IT Solutions BEGIN -->\n<div class=\"fb-like\" data-href=\"https:\/\/quizgp.com\/Hoa-Now\/architectural\/\" data-layout=\"standard\" data-action=\"like\" data-show-faces=\"false\" data-size=\"small\" data-width=\"450\" data-share=\"\" ><\/div>\n<!-- FB Like Button Starbit IT Solutions END -->\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"256\" src=\"https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/NEWSLETTER-Registration-20-1024x256.png?resize=1024%2C256&#038;ssl=1\" alt=\"\" class=\"wp-image-12583\" srcset=\"https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/NEWSLETTER-Registration-20.png?resize=1024%2C256&amp;ssl=1 1024w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/NEWSLETTER-Registration-20.png?resize=300%2C75&amp;ssl=1 300w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/NEWSLETTER-Registration-20.png?resize=768%2C192&amp;ssl=1 768w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/NEWSLETTER-Registration-20.png?resize=600%2C150&amp;ssl=1 600w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/NEWSLETTER-Registration-20.png?resize=1536%2C384&amp;ssl=1 1536w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/NEWSLETTER-Registration-20.png?resize=2048%2C512&amp;ssl=1 2048w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/NEWSLETTER-Registration-20.png?w=3000 3000w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<div style=\"height:67px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24-1024x1024.png?resize=1024%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-12584 size-full\" srcset=\"https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?w=1080&amp;ssl=1 1080w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Your Company <\/p>\n\n\n\n<p>Lic. #<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"108\" height=\"47\" src=\"https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Website-1.png?resize=108%2C47\" alt=\"\" class=\"wp-image-12391\"\/><\/figure>\n<\/div><\/div>\n\n\n\n<div style=\"height:67px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=1024%2C1024\" alt=\"\" class=\"wp-image-12584 size-full\" srcset=\"https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?w=1080&amp;ssl=1 1080w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Your Company <\/p>\n\n\n\n<p>Lic. #<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"108\" height=\"47\" src=\"https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Website-1.png?resize=108%2C47\" alt=\"\" class=\"wp-image-12391\"\/><\/figure>\n<\/div><\/div>\n\n\n\n<div style=\"height:67px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=1024%2C1024\" alt=\"\" class=\"wp-image-12584 size-full\" srcset=\"https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Untitled-design-24.png?w=1080&amp;ssl=1 1080w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Your Company <\/p>\n\n\n\n<p>Lic. #<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"108\" height=\"47\" src=\"https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Website-1.png?resize=108%2C47\" alt=\"\" class=\"wp-image-12391\"\/><\/figure>\n<\/div><\/div>\n\n\n\n<div style=\"height:67px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"392\" height=\"99\" src=\"https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Contractor-1.png?resize=392%2C99\" alt=\"\" class=\"wp-image-12371\" style=\"width:191px;height:auto\" srcset=\"https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Contractor-1.png?w=392&amp;ssl=1 392w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2026\/02\/Contractor-1.png?resize=300%2C76&amp;ssl=1 300w\" sizes=\"auto, (max-width: 392px) 100vw, 392px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-buttons has-custom-font-size has-large-font-size is-layout-flex wp-container-core-buttons-is-layout-1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size is-style-outline has-small-font-size is-style-outline--1\"><a class=\"wp-block-button__link has-vivid-cyan-blue-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/www.cslb.ca.gov\/onlineservices\/checklicenseII\/checklicense.aspx\">Check a Contractor License<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2021\/03\/linkedin-1-1.png?resize=300%2C300\" alt=\"\" class=\"wp-image-6148\" style=\"width:44px;height:auto\" srcset=\"https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2021\/03\/linkedin-1-1.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2021\/03\/linkedin-1-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2021\/03\/linkedin-1-1.png?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2021\/03\/linkedin-1-1.png?w=512&amp;ssl=1 512w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft is-resized\"><a href=\"https:\/\/www.instagram.com\/quizgp\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2021\/03\/instagram-1.png?resize=300%2C300\" alt=\"\" class=\"wp-image-6149\" style=\"width:42px;height:auto\" srcset=\"https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2021\/03\/instagram-1.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2021\/03\/instagram-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2021\/03\/instagram-1.png?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2021\/03\/instagram-1.png?w=512&amp;ssl=1 512w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"195\" height=\"195\" src=\"https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2025\/08\/x.png?resize=195%2C195\" alt=\"\" class=\"wp-image-11957\" style=\"width:43px;height:auto\" srcset=\"https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2025\/08\/x.png?w=195&amp;ssl=1 195w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2025\/08\/x.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/quizgp.com\/Hoa-Now\/wp-content\/uploads\/2025\/08\/x.png?resize=100%2C100&amp;ssl=1 100w\" sizes=\"auto, (max-width: 195px) 100vw, 195px\" \/><\/figure><\/div>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"Your Company Lic. # Your Company Lic. # Your Company Lic. # Check a Contractor License","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"jetpack_post_was_ever_published":false,"footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"class_list":["post-12582","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/P8JNUq-3gW","ticketed":false,"_links":{"self":[{"href":"https:\/\/quizgp.com\/Hoa-Now\/wp-json\/wp\/v2\/pages\/12582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quizgp.com\/Hoa-Now\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/quizgp.com\/Hoa-Now\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/quizgp.com\/Hoa-Now\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quizgp.com\/Hoa-Now\/wp-json\/wp\/v2\/comments?post=12582"}],"version-history":[{"count":1,"href":"https:\/\/quizgp.com\/Hoa-Now\/wp-json\/wp\/v2\/pages\/12582\/revisions"}],"predecessor-version":[{"id":12585,"href":"https:\/\/quizgp.com\/Hoa-Now\/wp-json\/wp\/v2\/pages\/12582\/revisions\/12585"}],"wp:attachment":[{"href":"https:\/\/quizgp.com\/Hoa-Now\/wp-json\/wp\/v2\/media?parent=12582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}